{"id":184,"date":"2025-09-04T13:50:00","date_gmt":"2025-09-04T11:50:00","guid":{"rendered":"https:\/\/event.esalsa.de\/jahrestagung25\/?post_type=speaker&#038;p=184"},"modified":"2025-10-23T16:18:17","modified_gmt":"2025-10-23T14:18:17","slug":"dr-klaus-wannemacher","status":"publish","type":"speaker","link":"https:\/\/event.esalsa.de\/jahrestagung25\/speaker\/dr-klaus-wannemacher\/","title":{"rendered":"Dr. Klaus Wannemacher"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Dr. Klaus Wannemacher ist Projektleiter im Gesch\u00e4ftsbereich Hochschulmanagement des HIS-Instituts f\u00fcr Hochschulentwicklung (HIS-HE). Als Organisationsberater unterst\u00fctzt er Hochschulen, au\u00dferuniversit\u00e4re Forschungseinrichtungen und Ministerien mit Beratungsleistungen, Forschungsprojekten und Angeboten zum Wissens- und Methodentransfer mit Schwerpunkten in den Bereichen Digitalisierung der Hochschulen und Entwicklung von Studium und Lehre.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"featured_media":185,"template":"","class_list":["post-184","speaker","type-speaker","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/event.esalsa.de\/jahrestagung25\/wp-json\/wp\/v2\/speaker\/184","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/event.esalsa.de\/jahrestagung25\/wp-json\/wp\/v2\/speaker"}],"about":[{"href":"https:\/\/event.esalsa.de\/jahrestagung25\/wp-json\/wp\/v2\/types\/speaker"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/event.esalsa.de\/jahrestagung25\/wp-json\/wp\/v2\/media\/185"}],"wp:attachment":[{"href":"https:\/\/event.esalsa.de\/jahrestagung25\/wp-json\/wp\/v2\/media?parent=184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}