{"id":199,"date":"2025-09-23T18:28:52","date_gmt":"2025-09-23T16:28:52","guid":{"rendered":"https:\/\/event.esalsa.de\/altmaerkische-netzwerkkonferenz-25\/?post_type=speaker&#038;p=199"},"modified":"2025-09-29T18:35:08","modified_gmt":"2025-09-29T16:35:08","slug":"prof-dr-volker-wiedemer","status":"publish","type":"speaker","link":"https:\/\/event.esalsa.de\/altmaerkische-netzwerkkonferenz-25\/speaker\/prof-dr-volker-wiedemer\/","title":{"rendered":"Prof. Dr. Volker Wiedemer"},"content":{"rendered":"\n<p>Hochschule Magdeburg-Stendal<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-199","speaker","type-speaker","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/event.esalsa.de\/altmaerkische-netzwerkkonferenz-25\/wp-json\/wp\/v2\/speaker\/199","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/event.esalsa.de\/altmaerkische-netzwerkkonferenz-25\/wp-json\/wp\/v2\/speaker"}],"about":[{"href":"https:\/\/event.esalsa.de\/altmaerkische-netzwerkkonferenz-25\/wp-json\/wp\/v2\/types\/speaker"}],"wp:attachment":[{"href":"https:\/\/event.esalsa.de\/altmaerkische-netzwerkkonferenz-25\/wp-json\/wp\/v2\/media?parent=199"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}